{"id":1,"count":4,"description":"","link":"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Uncategorized Archives - Mobile Driving School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized Archives - Mobile Driving School\" \/>\n<meta property=\"og:url\" content=\"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobile Driving School\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/\",\"url\":\"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/\",\"name\":\"Uncategorized Archives - Mobile Driving School\",\"isPartOf\":{\"@id\":\"https:\/\/mobiledriving.co.uk\/blog\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobiledriving.co.uk\/blog\/#website\",\"url\":\"https:\/\/mobiledriving.co.uk\/blog\/\",\"name\":\"Mobile Driving School\",\"description\":\"The Official Blog of Mobile Driving School\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobiledriving.co.uk\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized Archives - Mobile Driving School","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized Archives - Mobile Driving School","og_url":"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/","og_site_name":"Mobile Driving School","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/","url":"http:\/\/mobiledriving.co.uk\/blog\/category\/uncategorized\/","name":"Uncategorized Archives - Mobile Driving School","isPartOf":{"@id":"https:\/\/mobiledriving.co.uk\/blog\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/mobiledriving.co.uk\/blog\/#website","url":"https:\/\/mobiledriving.co.uk\/blog\/","name":"Mobile Driving School","description":"The Official Blog of Mobile Driving School","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobiledriving.co.uk\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/mobiledriving.co.uk\/blog\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"http:\/\/mobiledriving.co.uk\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/mobiledriving.co.uk\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/mobiledriving.co.uk\/blog\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}